{"id":12227,"date":"2024-05-17T14:12:26","date_gmt":"2024-05-17T18:12:26","guid":{"rendered":"https:\/\/www.millerthomson.com\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/"},"modified":"2024-05-17T14:12:26","modified_gmt":"2024-05-17T18:12:26","slug":"dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance","status":"publish","type":"post","link":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/","title":{"rendered":"Dons et cryptomonnaie : trucs et astuces pour les organismes de bienfaisance"},"content":{"rendered":"<p>Avec l\u2019explosion de la popularit\u00e9 de la cryptomonnaie, certains organismes de bienfaisance voient en cet actif une nouvelle strat\u00e9gie de collecte de fonds leur permettant de toucher un plus grand nombre de donateurs, et avec raison. \u00c0 titre d\u2019exemple, une \u00e9tude men\u00e9e en 2021 par Fidelity Charitable indiquait que 45% des investisseurs en cryptomonnaie ont donn\u00e9 1000$ ou plus \u00e0 des organismes de bienfaisance en 2020, contre 33% pour les investisseurs \u00ab\u00a0ordinaires\u00a0\u00bb<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>. Avant de s\u2019engager dans cette avenue, un organisme de bienfaisance se devrait toutefois d\u2019\u00e9laborer un plan de mise en \u0153uvre et de politiques claires lui permettant de g\u00e9rer les risques aff\u00e9rents \u00e0 ce type d\u2019actif et de se conformer \u00e0 ses obligations l\u00e9gales et fiscales.<\/p>\n<h2><strong>Consid\u00e9rations pratiques<\/strong><\/h2>\n<p>Les \u00a0organismes de bienfaisance ont plusieurs \u00e9l\u00e9ments \u00e0 consid\u00e9rer avant d\u2019accepter des dons en cryptomonnaie, tel que celui d\u2019examiner si ce type de financement est en accord avec les principes et les valeurs les gouvernant. Par exemple, consid\u00e9rant l\u2019impact environnemental d\u00e9coulant du minage de la cryptomonnaie, un organisme \u0153uvrant dans le secteur de la protection de l\u2019environnement pourrait se questionner si ce mode de financement lui convient, ou pourrait voir \u00e0 l\u2019adapter pour n\u2019accepter que des cryptomonnaies \u00ab\u00a0\u00e9coresponsables\u00a0\u00bb.<\/p>\n<p>Ensuite, pour accepter des dons en cryptomonnaie, plusieurs consid\u00e9rations pratiques doivent \u00eatre analys\u00e9es. Pour n\u2019en nommer que quelques-unes\u00a0:<\/p>\n<ul>\n<li>L\u2019organisme d\u00e9sire-t-il administrer personnellement son portefeuille de cryptomonnaie, ou recourir \u00e0 un tiers interm\u00e9diaire? Dans ce dernier cas, il devra effectuer certaines v\u00e9rifications pour s\u2019assurer que cet interm\u00e9diaire soit suffisamment s\u00e9curitaire et lui permette de respecter ses obligations au niveau de la <em>Loi de l\u2019imp\u00f4t sur le revenu <\/em>(Canada), des lois f\u00e9d\u00e9rales et des lois provinciales.<\/li>\n<li>La cryptomonnaie sera-t-elle conserv\u00e9e telle quelle, ou sera-telle plut\u00f4t convertie? Si la cryptomonnaie n\u2019est pas convertie, un organisme pourrait \u00eatre restreint \u00e0 transiger par l&rsquo;interm\u00e9diaire de la plateforme utilis\u00e9e et s\u2019exposer \u00e0 la volatilit\u00e9 des prix des cryptomonnaies. D\u2019ailleurs, il n\u2019est pas sans rappeler que tout d\u00e9pendamment de la province de r\u00e9sidence de l\u2019organisme de bienfaisance, celui-ci peut \u00eatre assujetti \u00e0 des r\u00e8gles restreignant les types d\u2019actifs qu\u2019il peut d\u00e9tenir, telles que celle de la r\u00e8gle de l\u2019\u00a0\u00ab\u00a0investisseur prudent\u00a0\u00bb. Ainsi, un organisme devra \u00e9galement se demander s\u2019il peut l\u00e9galement d\u00e9tenir de la cryptomonnaie.<\/li>\n<li>De quelle fa\u00e7on les dons seront-ils v\u00e9rifi\u00e9s pr\u00e9alablement \u00e0 leur acception? Un processus de v\u00e9rification diligente devra \u00eatre mis en place par l\u2019organisme de bienfaisance afin de notamment identifier le donateur, de s\u2019assurer que la donation n\u2019occasionne pas de risque pour la s\u00e9curit\u00e9 des donn\u00e9es de l\u2019organisation, ou que la donation ne soit pas en lien avec une activit\u00e9 criminelle ou terroriste.<\/li>\n<\/ul>\n<h2><strong>Re\u00e7us officiels de dons<\/strong><\/h2>\n<p>L\u2019\u00e9mission de re\u00e7us officiels de dons implique plusieurs responsabilit\u00e9s pour les organismes de bienfaisance, comme celle d\u2019y inscrire l\u2019ensemble des informations prescrites par la <em>Loi de l\u2019imp\u00f4t sur le revenu<\/em> (Canada) et de son r\u00e8glement, et de s\u2019assurer de la v\u00e9racit\u00e9 des informations y \u00e9tant inscrites, incluant la juste valeur marchande du don. <a href=\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social-fr\/cardinal-rules-donation-receipts\/\" target=\"_blank\" rel=\"noopener\">Pour davantage d\u2019information, lisez notre article discutant des r\u00e8gles entourant l\u2019\u00e9mission de re\u00e7us<\/a> (disponible en anglais seulement).<\/p>\n<p>Concernant ce dernier point, les organismes de bienfaisance doivent \u00eatre conscients qu\u2019un don de cryptomonnaie est consid\u00e9r\u00e9 par l\u2019Agence du Revenu du Canada (l\u2019\u00ab\u00a0ARC\u00a0\u00bb) comme en \u00e9tant un \u00ab\u00a0autre qu\u2019en esp\u00e8ces\u00a0\u00bb. Ainsi, les r\u00e8gles usuelles aff\u00e9rentes \u00e0 l\u2019\u00e9valuation de la juste valeur marchande et de la juste valeur marchande r\u00e9put\u00e9e s\u2019appliquent \u00e9galement aux dons de cryptomonnaie. \u00c0 cet \u00e9gard, l\u2019ARC mentionne dans son <a href=\"https:\/\/www.canada.ca\/fr\/agence-revenu\/programmes\/a-propos-agence-revenu-canada-arc\/observation\/monnaie-numerique\/cryptomonnaies-guide.html\" target=\"_blank\" rel=\"noopener\">guide<\/a> qu\u2019un contribuable se doit d\u2019utiliser une m\u00e9thode raisonnable pour d\u00e9terminer la valeur de la cryptomonnaie, par exemple en choisissant de mani\u00e8re constante un taux de change provenant du m\u00eame courtier en bourse, ou une moyenne des valeurs \u00e9lev\u00e9es\/faibles\/\u00e0 l\u2019ouverture\/\u00e0 la fermeture.<\/p>\n<p>Il est important de comprendre ces r\u00e8gles, car en cas d\u2019erreurs dans l\u2019\u00e9mission de re\u00e7us, non seulement les re\u00e7us peuvent \u00eatre annul\u00e9s, mais les organismes peuvent \u00eatre sujets \u00e0 d\u2019importantes p\u00e9nalit\u00e9s, ou voir m\u00eame \u00e0 la r\u00e9vocation de leur enregistrement.<\/p>\n<h2><strong>V\u00e9rification fiscale<\/strong><\/h2>\n<p>Depuis quelques ann\u00e9es, l\u2019ARC s\u2019int\u00e9resse de pr\u00e8s aux transactions de cryptomonnaie, et les organismes de bienfaisance n\u2019en \u00e9chappent pas. Tel qu\u2019\u00e9nonc\u00e9 dans son <em>Rapport sur le Programme des organismes de bienfaisance 2018 \u00e0 2020<\/em><a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>, l\u2019ARC a instaur\u00e9 de nouveaux projets d\u2019observation, incluant l\u2019examen de l\u2019utilisation de cryptomonnaie au sein du secteur de la bienfaisance.<\/p>\n<p>Ainsi, les organismes de bienfaisance songeant \u00e0 accepter des dons de cryptomonnaie devront adapter leur gestion de leur documentation afin de pouvoir r\u00e9pondre ad\u00e9quatement aux questions de l\u2019ARC.<\/p>\n<h2><strong>Conclusion<\/strong><\/h2>\n<p>La cryptomonnaie s\u2019av\u00e8re \u00eatre une nouvelle avenue pour les organismes de bienfaisance cherchant \u00e0 diversifier leurs strat\u00e9gies de collecte de fonds. Toutefois, en raison de la complexit\u00e9 inh\u00e9rente \u00e0 la cryptomonnaie, tout organisme de bienfaisance devrait pr\u00e9alablement se doter de politiques et de proc\u00e9dures gouvernant la prise de d\u00e9cisions, la gestion des risques, ainsi que la d\u00e9tention et le transfert de ce type d\u2019actif.<\/p>\n<p>Pour bien vous pr\u00e9parer \u00e0 recevoir des dons en cryptomonnaie, communiquez avec un membre de notre \u00e9quipe d\u2019<a href=\"https:\/\/www.millerthomson.com\/fr\/expertise\/impact-social\/\" target=\"_blank\" rel=\"noopener\">Impact social<\/a>.<\/p>\n<hr \/>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Fidelity Charitable, \u00ab\u00a0Cryptocurrency and philanthropy\u00a0\u00bb (disponible \u00e0 : <a href=\"https:\/\/www.fidelitycharitable.org\/insights\/cryptocurrency-and-philanthropy.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.fidelitycharitable.org\/insights\/cryptocurrency-and-philanthropy.html<\/a>)<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> ARC, \u00ab\u00a0Rapport sur le Programme des organismes de bienfaisance 2018 \u00e0 2020\u00a0\u00bb (disponible \u00e0\u00a0: <a href=\"https:\/\/www.canada.ca\/fr\/agence-revenu\/services\/organismes-bienfaisance-dons\/organismes-bienfaisance\/a-propos-direction-organismes-bienfaisance\/rapport-programme-organismes-bienfaisance\/rapport-programme-organismes-bienfaisance-2018-2020.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.canada.ca\/fr\/agence-revenu\/services\/organismes-bienfaisance-dons\/organismes-bienfaisance\/a-propos-direction-organismes-bienfaisance\/rapport-programme-organismes-bienfaisance\/rapport-programme-organismes-bienfaisance-2018-2020.html<\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec l\u2019explosion de la popularit\u00e9 de la cryptomonnaie, certains organismes de bienfaisance voient en cet actif une nouvelle strat\u00e9gie de collecte de fonds leur permettant de toucher un plus grand nombre de donateurs, et avec raison. \u00c0 titre d\u2019exemple, une \u00e9tude men\u00e9e en 2021 par Fidelity Charitable indiquait que 45% des investisseurs en cryptomonnaie ont [&hellip;]<\/p>\n","protected":false},"author":86,"featured_media":14389,"parent":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[588],"insight-format":[],"class_list":["post-12227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-impact-social"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dons et cryptomonnaie : trucs et astuces pour les organismes de bienfaisance | Miller Thomson<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dons et cryptomonnaie : trucs et astuces pour les organismes de bienfaisance | Miller Thomson\" \/>\n<meta property=\"og:description\" content=\"Avec l\u2019explosion de la popularit\u00e9 de la cryptomonnaie, certains organismes de bienfaisance voient en cet actif une nouvelle strat\u00e9gie de collecte de fonds leur permettant de toucher un plus grand nombre de donateurs, et avec raison. \u00c0 titre d\u2019exemple, une \u00e9tude men\u00e9e en 2021 par Fidelity Charitable indiquait que 45% des investisseurs en cryptomonnaie ont [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/\" \/>\n<meta property=\"og:site_name\" content=\"Miller Thomson\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MillerThomsonLaw\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-17T18:12:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insights_Social-Impact_Post-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1776\" \/>\n\t<meta property=\"og:image:height\" content=\"994\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nyeisha Murray\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@millerthomson\" \/>\n<meta name=\"twitter:site\" content=\"@millerthomson\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nyeisha Murray\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/\"},\"author\":{\"name\":\"Nyeisha Murray\",\"@id\":\"https:\/\/www.millerthomson.com\/fr\/#\/schema\/person\/8c49b710501a2ba22438ca72fb0c0c85\"},\"headline\":\"Dons et cryptomonnaie : trucs et astuces pour les organismes de bienfaisance\",\"datePublished\":\"2024-05-17T18:12:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/\"},\"wordCount\":975,\"publisher\":{\"@id\":\"https:\/\/www.millerthomson.com\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insights_Social-Impact_Post-Image.jpg\",\"articleSection\":[\"Impact Social\"],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/\",\"url\":\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/\",\"name\":\"Dons et cryptomonnaie : trucs et astuces pour les organismes de bienfaisance | Miller Thomson\",\"isPartOf\":{\"@id\":\"https:\/\/www.millerthomson.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insights_Social-Impact_Post-Image.jpg\",\"datePublished\":\"2024-05-17T18:12:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#primaryimage\",\"url\":\"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insights_Social-Impact_Post-Image.jpg\",\"contentUrl\":\"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insights_Social-Impact_Post-Image.jpg\",\"width\":1776,\"height\":994,\"caption\":\"people standing in a circle with hands extended towards the middle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.millerthomson.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dons et cryptomonnaie : trucs et astuces pour les organismes de bienfaisance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.millerthomson.com\/fr\/#website\",\"url\":\"https:\/\/www.millerthomson.com\/fr\/\",\"name\":\"Miller Thomson | Cabinet de droit des affaires pancanadien\",\"description\":\"National law firm providing business law expertise and litigation and disputes services for businesses across Canada since 1957.\",\"publisher\":{\"@id\":\"https:\/\/www.millerthomson.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.millerthomson.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.millerthomson.com\/fr\/#organization\",\"name\":\"Miller Thomson | Cabinet de droit des affaires pancanadien\",\"url\":\"https:\/\/www.millerthomson.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.millerthomson.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/miller-thomson.svg\",\"contentUrl\":\"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/miller-thomson.svg\",\"width\":380,\"height\":50,\"caption\":\"Miller Thomson | Cabinet de droit des affaires pancanadien\"},\"image\":{\"@id\":\"https:\/\/www.millerthomson.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MillerThomsonLaw\/\",\"https:\/\/x.com\/millerthomson\",\"https:\/\/www.linkedin.com\/company\/miller-thomson-llp\/\",\"https:\/\/www.youtube.com\/@millerthomson\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.millerthomson.com\/fr\/#\/schema\/person\/8c49b710501a2ba22438ca72fb0c0c85\",\"name\":\"Nyeisha Murray\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.millerthomson.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ec01113c3c7208ac683f05f5b7f25e187ddf5deabc82d0d9e12aeca8d3b9c851?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ec01113c3c7208ac683f05f5b7f25e187ddf5deabc82d0d9e12aeca8d3b9c851?s=96&d=mm&r=g\",\"caption\":\"Nyeisha Murray\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dons et cryptomonnaie : trucs et astuces pour les organismes de bienfaisance | Miller Thomson","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/","og_locale":"fr_FR","og_type":"article","og_title":"Dons et cryptomonnaie : trucs et astuces pour les organismes de bienfaisance | Miller Thomson","og_description":"Avec l\u2019explosion de la popularit\u00e9 de la cryptomonnaie, certains organismes de bienfaisance voient en cet actif une nouvelle strat\u00e9gie de collecte de fonds leur permettant de toucher un plus grand nombre de donateurs, et avec raison. \u00c0 titre d\u2019exemple, une \u00e9tude men\u00e9e en 2021 par Fidelity Charitable indiquait que 45% des investisseurs en cryptomonnaie ont [&hellip;]","og_url":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/","og_site_name":"Miller Thomson","article_publisher":"https:\/\/www.facebook.com\/MillerThomsonLaw\/","article_published_time":"2024-05-17T18:12:26+00:00","og_image":[{"width":1776,"height":994,"url":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insights_Social-Impact_Post-Image.jpg","type":"image\/jpeg"}],"author":"Nyeisha Murray","twitter_card":"summary_large_image","twitter_creator":"@millerthomson","twitter_site":"@millerthomson","twitter_misc":{"Written by":"Nyeisha Murray","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#article","isPartOf":{"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/"},"author":{"name":"Nyeisha Murray","@id":"https:\/\/www.millerthomson.com\/fr\/#\/schema\/person\/8c49b710501a2ba22438ca72fb0c0c85"},"headline":"Dons et cryptomonnaie : trucs et astuces pour les organismes de bienfaisance","datePublished":"2024-05-17T18:12:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/"},"wordCount":975,"publisher":{"@id":"https:\/\/www.millerthomson.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insights_Social-Impact_Post-Image.jpg","articleSection":["Impact Social"],"inLanguage":"fr-FR"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/","url":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/","name":"Dons et cryptomonnaie : trucs et astuces pour les organismes de bienfaisance | Miller Thomson","isPartOf":{"@id":"https:\/\/www.millerthomson.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#primaryimage"},"image":{"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insights_Social-Impact_Post-Image.jpg","datePublished":"2024-05-17T18:12:26+00:00","breadcrumb":{"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#primaryimage","url":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insights_Social-Impact_Post-Image.jpg","contentUrl":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insights_Social-Impact_Post-Image.jpg","width":1776,"height":994,"caption":"people standing in a circle with hands extended towards the middle"},{"@type":"BreadcrumbList","@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/impact-social\/dons-cryptomonnaie-trucs-astuces-les-organismes-bienfaisance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.millerthomson.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Dons et cryptomonnaie : trucs et astuces pour les organismes de bienfaisance"}]},{"@type":"WebSite","@id":"https:\/\/www.millerthomson.com\/fr\/#website","url":"https:\/\/www.millerthomson.com\/fr\/","name":"Miller Thomson | Cabinet de droit des affaires pancanadien","description":"National law firm providing business law expertise and litigation and disputes services for businesses across Canada since 1957.","publisher":{"@id":"https:\/\/www.millerthomson.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.millerthomson.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.millerthomson.com\/fr\/#organization","name":"Miller Thomson | Cabinet de droit des affaires pancanadien","url":"https:\/\/www.millerthomson.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.millerthomson.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/miller-thomson.svg","contentUrl":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/miller-thomson.svg","width":380,"height":50,"caption":"Miller Thomson | Cabinet de droit des affaires pancanadien"},"image":{"@id":"https:\/\/www.millerthomson.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MillerThomsonLaw\/","https:\/\/x.com\/millerthomson","https:\/\/www.linkedin.com\/company\/miller-thomson-llp\/","https:\/\/www.youtube.com\/@millerthomson"]},{"@type":"Person","@id":"https:\/\/www.millerthomson.com\/fr\/#\/schema\/person\/8c49b710501a2ba22438ca72fb0c0c85","name":"Nyeisha Murray","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.millerthomson.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ec01113c3c7208ac683f05f5b7f25e187ddf5deabc82d0d9e12aeca8d3b9c851?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec01113c3c7208ac683f05f5b7f25e187ddf5deabc82d0d9e12aeca8d3b9c851?s=96&d=mm&r=g","caption":"Nyeisha Murray"}}]}},"_links":{"self":[{"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/posts\/12227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/comments?post=12227"}],"version-history":[{"count":0,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/posts\/12227\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/media\/14389"}],"wp:attachment":[{"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/media?parent=12227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/categories?post=12227"},{"taxonomy":"insight-format","embeddable":true,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/insight-format?post=12227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}