{"id":12206,"date":"2024-04-16T13:38:31","date_gmt":"2024-04-16T17:38:31","guid":{"rendered":"https:\/\/www.millerthomson.com\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/"},"modified":"2024-04-16T13:38:31","modified_gmt":"2024-04-16T17:38:31","slug":"lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec","status":"publish","type":"post","link":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/","title":{"rendered":"L\u2019intervention forc\u00e9e et l\u2019appel en garantie : analyse r\u00e9cente de la cour sup\u00e9rieure du Qu\u00e9bec"},"content":{"rendered":"<p>Le <em>Code de proc\u00e9dure civile<\/em> <strong>c-25.01<\/strong><strong>\u00a0<\/strong> (C.p.c.) du Qu\u00e9bec met notamment \u00e0 la disposition des justiciables deux m\u00e9canismes proc\u00e9duraux afin de faire intervenir un tiers \u00e0 l\u2019instance, soit (1) l\u2019appel en garantie qui permet d\u2019\u00eatre indemnis\u00e9 d\u2019une condamnation \u00e9ventuelle et (2) la mise en cause forc\u00e9e qui permet l\u2019ajout d\u2019une nouvelle partie au litige \u00e0 titre de co-d\u00e9fenderesse.<\/p>\n<p>Ces m\u00e9canismes sont r\u00e9guli\u00e8rement utilis\u00e9s devant les tribunaux pour permettre aux parties d\u2019impliquer l\u2019ensemble des intervenants vis\u00e9s par un litige. Or, dans une d\u00e9cision r\u00e9cente<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>, la Cour Sup\u00e9rieure, sous la plume de l\u2019honorable juge Pierre Nollet, rappelle que ces demandes sont soumises \u00e0 des crit\u00e8res sp\u00e9cifiques, lesquels se doivent d\u2019\u00eatre respect\u00e9s, sous peine de rejet de la demande d\u2019intervention forc\u00e9e ou de la demande en garantie.<\/p>\n<h2>CONTEXTE<\/h2>\n<p>Dans le dossier sous \u00e9tude, le locateur de diff\u00e9rents espaces commerciaux situ\u00e9s dans le centre commercial CF Promenades St-Bruno \u00e0 Saint-Bruno-de-Montarville, poursuit les d\u00e9fenderesses, locataires desdits espaces commerciaux pour des loyers impay\u00e9s, des dommages pour d\u00e9guerpissement pendant le bail et des dommages pour enl\u00e8vement de biens appartenant au locateur dans le cadre d\u2019un recours ayant une valeur de plus de $1.4M.<\/p>\n<p>De leur c\u00f4t\u00e9, les d\u00e9fenderesses all\u00e8guent en d\u00e9fense avoir sign\u00e9 les baux sous de fausses repr\u00e9sentations qu\u2019elles pr\u00e9tendent avoir \u00e9t\u00e9 faites par le locateur ainsi que Live Work Learn and Play inc. (\u00ab\u00a0<strong>LWLP<\/strong>\u00a0\u00bb), mandat\u00e9e par le locateur pour revitaliser le centre commercial. Les d\u00e9fenderesses ont ainsi introduit un <em>Acte d\u2019intervention forc\u00e9 pour appel en garantie et mise en cause forc\u00e9e<\/em> contre LWLP<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a> afin que celle-ci soit tenue d\u2019assumer les cons\u00e9quences de la r\u00e9clamation du locateur. Dans le cadre de leur recours contre LWLP, les d\u00e9fenderesses soutenaient essentiellement que la pr\u00e9sence de LWLP \u00e9tait indispensable afin de r\u00e9soudre le litige et \u00e9viter la r\u00e9p\u00e9tition inutile et co\u00fbteuse des m\u00eames d\u00e9bats, consid\u00e9rant son r\u00f4le dans le cadre de la revitalisation du centre commercial et les reproches formul\u00e9s. Les d\u00e9fenderesses se disaient aussi en droit d\u2019\u00eatre indemnis\u00e9es par LWLP de toutes les cons\u00e9quences d\u2019un jugement d\u00e9favorable dans le cadre de l\u2019action principale introduite par le locateur.<\/p>\n<p>LWLP s\u2019est oppos\u00e9e \u00e0 sa mise en cause forc\u00e9e et \u00e0 l\u2019appel en garantie et a pr\u00e9sent\u00e9 une demande en rejet. LWLP a eu gain de cause, pour les motifs ci-apr\u00e8s consid\u00e9r\u00e9s par le juge Nollet<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>.<\/p>\n<h2>L\u2019OPPOSITION \u00c0 LA MISE EN CAUSE FORC\u00c9E<\/h2>\n<p>Le tribunal rappelle d\u2019abord qu\u2019en cas d\u2019opposition, le fardeau de prouver que la mise en cause est n\u00e9cessaire reposait sur les \u00e9paules de la partie qui a mis le tiers en cause, dans ce cas-ci, les d\u00e9fenderesses. Les tribunaux se sont d\u2019ailleurs montr\u00e9s exigeants sur l\u2019application du crit\u00e8re de la n\u00e9cessit\u00e9, en ce qu\u2019il ne suffit pas que la mise en cause soit utile, mais plut\u00f4t n\u00e9cessaire.<\/p>\n<p>Les d\u00e9fenderesses plaidaient l\u2019existence d\u2019une connexit\u00e9 entre le litige principal et la mise en cause forc\u00e9e. Or, la Cour souligne que c\u2019est \u00e0 l\u2019aune du recours principal, soit une r\u00e9clamation d\u2019arr\u00e9rages de loyers, de dommages li\u00e9s \u00e0 la terminaison par anticipation des baux et ceux reli\u00e9s \u00e0 l\u2019enl\u00e8vement des biens sans droits, que devait s\u2019appr\u00e9cier le crit\u00e8re de la n\u00e9cessit\u00e9.<\/p>\n<p>Ainsi, m\u00eame si les d\u00e9fenderesses all\u00e9guaient l\u2019existence d\u2019une faute extracontractuelle pr\u00e9tendument commise par LWLP \u00e0 titre de mandataire du locateur, soit de pr\u00e9tendues fausses repr\u00e9sentations au moment de la conclusion des baux, il \u00e9tait impossible que LWLP soit condamn\u00e9e au paiement des arr\u00e9rages de loyers, du loyer futur et encore moins des dommages reli\u00e9s \u00e0 l\u2019enl\u00e8vement des am\u00e9liorations locatives. Le principe de la relativit\u00e9 des contrats s\u2019y oppose.<\/p>\n<p>Par cons\u00e9quent, et comme la mise en cause forc\u00e9e ne soulevait pas le m\u00eame d\u00e9bat que l\u2019action principale, le risque de jugement contradictoire devenait nul. Le crit\u00e8re de n\u00e9cessit\u00e9 n\u2019\u00e9tait pas rempli. L\u2019intervention forc\u00e9e \u00e9tait donc mal fond\u00e9e en droit.<\/p>\n<h2>L\u2019APPEL EN GARANTIE<\/h2>\n<p>Le tribunal rappelle que l\u2019appel en garantie pr\u00e9suppose un lien de droit entre celui qui appelle en garantie et l\u2019appel\u00e9 en garantie. Tr\u00e8s souvent, ce lien sera de nature contractuelle. Dans l\u2019affaire sous \u00e9tude, les d\u00e9fenderesses argumentaient que la faute extracontractuelle de LWLP venait cr\u00e9er ce lien de droit.<\/p>\n<p>Or, le tribunal souligne que pour qu\u2019une telle situation puisse s\u2019appliquer, une <strong>solidarit\u00e9 potentielle<\/strong> entre celui qui forme l\u2019appel en garantie et l\u2019appel\u00e9 en garantie <u>doit exister<\/u>. Ce n\u2019\u00e9tait pas le cas dans la pr\u00e9sente affaire. En effet, le juge Nollet conclut qu\u2019il n\u2019y avait aucune chance que le reproche de nature contractuelle pesant sur les d\u00e9fenderesses puisse \u00eatre fait \u00e0 LWLP, m\u00eame dans l\u2019\u00e9ventualit\u00e9 o\u00f9 les fausses repr\u00e9sentations all\u00e9gu\u00e9es \u00e9taient prouv\u00e9es.<\/p>\n<p>Par cons\u00e9quent, l\u2019honorable juge Nollet a rejet\u00e9 l\u2019appel en garantie et la mise en cause forc\u00e9e des d\u00e9fenderesses contre LWLP.<\/p>\n<p>En r\u00e9sum\u00e9, cette d\u00e9cision illustre l\u2019importance de respecter les crit\u00e8res sp\u00e9cifiques et pr\u00e9cis applicables \u00e0 l\u2019intervention forc\u00e9e et l\u2019appel en garantie. L\u2019ajout d\u2019un tiers au litige est loin d\u2019\u00eatre un automatisme. Telle proc\u00e9dure n\u00e9cessite une justification en droit. Cette affaire r\u00e9affirme la rigueur avec laquelle les avocats doivent \u00e9valuer les demandes d&rsquo;intervention forc\u00e9e et appels en garantie ainsi que celle avec laquelle les tribunaux appliquent les crit\u00e8res en jeu.<\/p>\n<hr \/>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> \u00a0\u00a0\u00a0 Dossier de Cour 505-17-013697-232.<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> \u00a0\u00a0\u00a0 Repr\u00e9sent\u00e9e par Miller Thomson.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> \u00a0\u00a0\u00a0 Me Jasmine de Guise du cabinet Miller Thomson a plaid\u00e9 avec succ\u00e8s la demande d\u2019opposition et en rejet de LWLP dans cette affaire. Cette d\u00e9cision n\u2019a pas \u00e9t\u00e9 port\u00e9e en appel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Code de proc\u00e9dure civile c-25.01\u00a0 (C.p.c.) du Qu\u00e9bec met notamment \u00e0 la disposition des justiciables deux m\u00e9canismes proc\u00e9duraux afin de faire intervenir un tiers \u00e0 l\u2019instance, soit (1) l\u2019appel en garantie qui permet d\u2019\u00eatre indemnis\u00e9 d\u2019une condamnation \u00e9ventuelle et (2) la mise en cause forc\u00e9e qui permet l\u2019ajout d\u2019une nouvelle partie au litige \u00e0 [&hellip;]<\/p>\n","protected":false},"author":86,"featured_media":14400,"parent":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[598],"insight-format":[],"class_list":["post-12206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-litige-commercial"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019intervention forc\u00e9e et l\u2019appel en garantie : analyse r\u00e9cente de la cour sup\u00e9rieure du Qu\u00e9bec | Miller Thomson<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019intervention forc\u00e9e et l\u2019appel en garantie : analyse r\u00e9cente de la cour sup\u00e9rieure du Qu\u00e9bec | Miller Thomson\" \/>\n<meta property=\"og:description\" content=\"Le Code de proc\u00e9dure civile c-25.01\u00a0 (C.p.c.) du Qu\u00e9bec met notamment \u00e0 la disposition des justiciables deux m\u00e9canismes proc\u00e9duraux afin de faire intervenir un tiers \u00e0 l\u2019instance, soit (1) l\u2019appel en garantie qui permet d\u2019\u00eatre indemnis\u00e9 d\u2019une condamnation \u00e9ventuelle et (2) la mise en cause forc\u00e9e qui permet l\u2019ajout d\u2019une nouvelle partie au litige \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/\" \/>\n<meta property=\"og:site_name\" content=\"Miller Thomson\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MillerThomsonLaw\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T17:38:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insigths_Commercial-Litigation_Post-Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1776\" \/>\n\t<meta property=\"og:image:height\" content=\"994\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nyeisha Murray\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@millerthomson\" \/>\n<meta name=\"twitter:site\" content=\"@millerthomson\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nyeisha Murray\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/perspectives-juridiques\\\/litige-commercial\\\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/perspectives-juridiques\\\/litige-commercial\\\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\\\/\"},\"author\":{\"name\":\"Nyeisha Murray\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#\\\/schema\\\/person\\\/8c49b710501a2ba22438ca72fb0c0c85\"},\"headline\":\"L\u2019intervention forc\u00e9e et l\u2019appel en garantie : analyse r\u00e9cente de la cour sup\u00e9rieure du Qu\u00e9bec\",\"datePublished\":\"2024-04-16T17:38:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/perspectives-juridiques\\\/litige-commercial\\\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\\\/\"},\"wordCount\":1063,\"publisher\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/perspectives-juridiques\\\/litige-commercial\\\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.millerthomson.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Insigths_Commercial-Litigation_Post-Image.jpg\",\"articleSection\":[\"Litige commercial\"],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/perspectives-juridiques\\\/litige-commercial\\\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\\\/\",\"url\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/perspectives-juridiques\\\/litige-commercial\\\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\\\/\",\"name\":\"L\u2019intervention forc\u00e9e et l\u2019appel en garantie : analyse r\u00e9cente de la cour sup\u00e9rieure du Qu\u00e9bec | Miller Thomson\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/perspectives-juridiques\\\/litige-commercial\\\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/perspectives-juridiques\\\/litige-commercial\\\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.millerthomson.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Insigths_Commercial-Litigation_Post-Image.jpg\",\"datePublished\":\"2024-04-16T17:38:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/perspectives-juridiques\\\/litige-commercial\\\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/perspectives-juridiques\\\/litige-commercial\\\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/perspectives-juridiques\\\/litige-commercial\\\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.millerthomson.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Insigths_Commercial-Litigation_Post-Image.jpg\",\"contentUrl\":\"https:\\\/\\\/www.millerthomson.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Insigths_Commercial-Litigation_Post-Image.jpg\",\"width\":1776,\"height\":994},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/perspectives-juridiques\\\/litige-commercial\\\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019intervention forc\u00e9e et l\u2019appel en garantie : analyse r\u00e9cente de la cour sup\u00e9rieure du Qu\u00e9bec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/\",\"name\":\"Miller Thomson | Cabinet de droit des affaires pancanadien\",\"description\":\"National law firm providing business law expertise and litigation and disputes services for businesses across Canada since 1957.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#organization\",\"name\":\"Miller Thomson | Cabinet de droit des affaires pancanadien\",\"url\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.millerthomson.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/miller-thomson.svg\",\"contentUrl\":\"https:\\\/\\\/www.millerthomson.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/miller-thomson.svg\",\"width\":380,\"height\":50,\"caption\":\"Miller Thomson | Cabinet de droit des affaires pancanadien\"},\"image\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MillerThomsonLaw\\\/\",\"https:\\\/\\\/x.com\\\/millerthomson\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/miller-thomson-llp\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@millerthomson\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#\\\/schema\\\/person\\\/8c49b710501a2ba22438ca72fb0c0c85\",\"name\":\"Nyeisha Murray\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec01113c3c7208ac683f05f5b7f25e187ddf5deabc82d0d9e12aeca8d3b9c851?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec01113c3c7208ac683f05f5b7f25e187ddf5deabc82d0d9e12aeca8d3b9c851?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec01113c3c7208ac683f05f5b7f25e187ddf5deabc82d0d9e12aeca8d3b9c851?s=96&d=mm&r=g\",\"caption\":\"Nyeisha Murray\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019intervention forc\u00e9e et l\u2019appel en garantie : analyse r\u00e9cente de la cour sup\u00e9rieure du Qu\u00e9bec | Miller Thomson","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019intervention forc\u00e9e et l\u2019appel en garantie : analyse r\u00e9cente de la cour sup\u00e9rieure du Qu\u00e9bec | Miller Thomson","og_description":"Le Code de proc\u00e9dure civile c-25.01\u00a0 (C.p.c.) du Qu\u00e9bec met notamment \u00e0 la disposition des justiciables deux m\u00e9canismes proc\u00e9duraux afin de faire intervenir un tiers \u00e0 l\u2019instance, soit (1) l\u2019appel en garantie qui permet d\u2019\u00eatre indemnis\u00e9 d\u2019une condamnation \u00e9ventuelle et (2) la mise en cause forc\u00e9e qui permet l\u2019ajout d\u2019une nouvelle partie au litige \u00e0 [&hellip;]","og_url":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/","og_site_name":"Miller Thomson","article_publisher":"https:\/\/www.facebook.com\/MillerThomsonLaw\/","article_published_time":"2024-04-16T17:38:31+00:00","og_image":[{"width":1776,"height":994,"url":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insigths_Commercial-Litigation_Post-Image.jpg","type":"image\/jpeg"}],"author":"Nyeisha Murray","twitter_card":"summary_large_image","twitter_creator":"@millerthomson","twitter_site":"@millerthomson","twitter_misc":{"Written by":"Nyeisha Murray","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/#article","isPartOf":{"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/"},"author":{"name":"Nyeisha Murray","@id":"https:\/\/www.millerthomson.com\/fr\/#\/schema\/person\/8c49b710501a2ba22438ca72fb0c0c85"},"headline":"L\u2019intervention forc\u00e9e et l\u2019appel en garantie : analyse r\u00e9cente de la cour sup\u00e9rieure du Qu\u00e9bec","datePublished":"2024-04-16T17:38:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/"},"wordCount":1063,"publisher":{"@id":"https:\/\/www.millerthomson.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/#primaryimage"},"thumbnailUrl":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insigths_Commercial-Litigation_Post-Image.jpg","articleSection":["Litige commercial"],"inLanguage":"fr-FR"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/","url":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/","name":"L\u2019intervention forc\u00e9e et l\u2019appel en garantie : analyse r\u00e9cente de la cour sup\u00e9rieure du Qu\u00e9bec | Miller Thomson","isPartOf":{"@id":"https:\/\/www.millerthomson.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/#primaryimage"},"image":{"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/#primaryimage"},"thumbnailUrl":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insigths_Commercial-Litigation_Post-Image.jpg","datePublished":"2024-04-16T17:38:31+00:00","breadcrumb":{"@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/#primaryimage","url":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insigths_Commercial-Litigation_Post-Image.jpg","contentUrl":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/Insigths_Commercial-Litigation_Post-Image.jpg","width":1776,"height":994},{"@type":"BreadcrumbList","@id":"https:\/\/www.millerthomson.com\/fr\/perspectives-juridiques\/litige-commercial\/lintervention-forcee-lappel-en-garantie-analyse-la-cour-superieure-du-quebec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.millerthomson.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019intervention forc\u00e9e et l\u2019appel en garantie : analyse r\u00e9cente de la cour sup\u00e9rieure du Qu\u00e9bec"}]},{"@type":"WebSite","@id":"https:\/\/www.millerthomson.com\/fr\/#website","url":"https:\/\/www.millerthomson.com\/fr\/","name":"Miller Thomson | Cabinet de droit des affaires pancanadien","description":"National law firm providing business law expertise and litigation and disputes services for businesses across Canada since 1957.","publisher":{"@id":"https:\/\/www.millerthomson.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.millerthomson.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.millerthomson.com\/fr\/#organization","name":"Miller Thomson | Cabinet de droit des affaires pancanadien","url":"https:\/\/www.millerthomson.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.millerthomson.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/miller-thomson.svg","contentUrl":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/miller-thomson.svg","width":380,"height":50,"caption":"Miller Thomson | Cabinet de droit des affaires pancanadien"},"image":{"@id":"https:\/\/www.millerthomson.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MillerThomsonLaw\/","https:\/\/x.com\/millerthomson","https:\/\/www.linkedin.com\/company\/miller-thomson-llp\/","https:\/\/www.youtube.com\/@millerthomson"]},{"@type":"Person","@id":"https:\/\/www.millerthomson.com\/fr\/#\/schema\/person\/8c49b710501a2ba22438ca72fb0c0c85","name":"Nyeisha Murray","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ec01113c3c7208ac683f05f5b7f25e187ddf5deabc82d0d9e12aeca8d3b9c851?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ec01113c3c7208ac683f05f5b7f25e187ddf5deabc82d0d9e12aeca8d3b9c851?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec01113c3c7208ac683f05f5b7f25e187ddf5deabc82d0d9e12aeca8d3b9c851?s=96&d=mm&r=g","caption":"Nyeisha Murray"}}]}},"_links":{"self":[{"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/posts\/12206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/comments?post=12206"}],"version-history":[{"count":0,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/posts\/12206\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/media\/14400"}],"wp:attachment":[{"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/media?parent=12206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/categories?post=12206"},{"taxonomy":"insight-format","embeddable":true,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/insight-format?post=12206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}