{"id":46642,"date":"2026-02-09T08:58:00","date_gmt":"2026-02-09T13:58:00","guid":{"rendered":"https:\/\/www.millerthomson.com\/deals-cases\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\/"},"modified":"2026-02-17T09:23:21","modified_gmt":"2026-02-17T14:23:21","slug":"court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy","status":"publish","type":"deals-cases","link":"https:\/\/www.millerthomson.com\/fr\/transactions-et-causes\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\/","title":{"rendered":"Faillite de Grozelle\u00a0: Le tribunal ordonne le recouvrement des 21,5\u00a0millions de dollars \u00ab\u00a0gagn\u00e9s\u00a0\u00bb dans le cadre d\u2019une fraude de type Ponzi"},"content":{"rendered":"\n<p>Le 9&nbsp;f\u00e9vrier&nbsp;2026, la Cour sup\u00e9rieure de justice de l\u2019Ontario a publi\u00e9 ses motifs dans une d\u00e9cision importante pour le droit canadien de l\u2019insolvabilit\u00e9 dans l\u2019affaire de la faillite de Douglas Grozelle (2026&nbsp;ONSC&nbsp;758).<\/p>\n\n\n\n<p>La Cour a accueilli une demande d\u00e9pos\u00e9e par Grant Thornton Limited, en sa qualit\u00e9 de syndic de faillite de Douglas Grozelle, visant \u00e0 recouvrer environ 21,5&nbsp;millions de dollars en \u00ab&nbsp;int\u00e9r\u00eats&nbsp;\u00bb fictifs vers\u00e9s \u00e0 120&nbsp;\u00ab&nbsp;gagnants nets&nbsp;\u00bb. Les fonds recouvr\u00e9s seront utilis\u00e9s par le syndic pour indemniser les 116&nbsp;victimes ayant perdu leur investissement dans la fraude.<\/p>\n\n\n\n<p>De 2021 \u00e0 2023, Douglas Grozelle a orchestr\u00e9 une fraude de type Ponzi sous la forme d\u2019une activit\u00e9 de pr\u00eats-relais immobiliers \u00e0 court terme. Il a recycl\u00e9 103&nbsp;millions de dollars par le biais de transactions bancaires, promettant aux investisseurs des taux d\u2019int\u00e9r\u00eat annuels exorbitants, pouvant atteindre 18,250 %, vers\u00e9s gr\u00e2ce aux fonds provenant d\u2019investisseurs ult\u00e9rieurs.<\/p>\n\n\n\n<p><strong>Principales conclusions<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Cession en fraude des droits des cr\u00e9anciers\u00a0:<\/strong> Le juge F. L. Myers a conclu que les paiements d\u00e9passant le remboursement du capital des investisseurs \u00e9taient nuls \u00e0 l\u2019encontre du syndic, en vertu de la <em>Loi sur les cessions en fraude des droits des cr\u00e9anciers<\/em>, car ils visaient \u00e0 frauder, entraver ou frustrer les autres cr\u00e9anciers.<\/li>\n\n\n\n<li><strong>Insolvabilit\u00e9 d\u00e8s le d\u00e9but\u00a0:<\/strong> La Cour a r\u00e9affirm\u00e9 que les fraudes de type Ponzi sont r\u00e9put\u00e9es insolvables en droit d\u00e8s leur d\u00e9but.<\/li>\n\n\n\n<li><strong>Primaut\u00e9 de la substance sur la forme\u00a0:<\/strong> Le tribunal a rejet\u00e9 l\u2019argument selon lequel les investissements constituaient des \u00ab\u00a0pr\u00eats l\u00e9gaux\u00a0\u00bb, estimant que les billets \u00e0 ordre n\u2019\u00e9taient en r\u00e9alit\u00e9 que des outils de marketing servant un stratag\u00e8me frauduleux.<\/li>\n<\/ul>\n\n\n\n<p>L\u2019enqu\u00eate du syndic a r\u00e9pertori\u00e9 un total de 236&nbsp;investisseurs. Alors que 116&nbsp;d\u2019entre eux ont subi une perte combin\u00e9e de 24,5&nbsp;millions de dollars, les 120&nbsp;\u00ab&nbsp;gagnants nets&nbsp;\u00bb ont re\u00e7u 49,9&nbsp;millions de dollars, soit l\u2019int\u00e9gralit\u00e9 de leur capital ainsi qu\u2019un b\u00e9n\u00e9fice fictif de 21,5&nbsp;millions de dollars. L\u2019ordonnance du tribunal assure un partage \u00e9quitable des actifs en exigeant que ces \u00ab&nbsp;gagnants&nbsp;\u00bb restituent les b\u00e9n\u00e9fices fictifs de l\u2019actif du failli administr\u00e9 par Grant Thornton Limited.<\/p>\n\n\n\n<p>L\u2019\u00e9quipe de Miller Thomson qui a repr\u00e9sent\u00e9 Grant Thornton Limited (syndic de faillite) \u00e9tait compos\u00e9e de David Ward, Mryam Sarkis et Armando Ranjbar.<\/p>\n","protected":false},"author":92,"template":"","class_list":["post-46642","deals-cases","type-deals-cases","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Faillite de Grozelle\u00a0: Le tribunal ordonne le recouvrement des 21,5\u00a0millions de dollars \u00ab\u00a0gagn\u00e9s\u00a0\u00bb dans le cadre d\u2019une fraude de type Ponzi | Miller Thomson<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.millerthomson.com\/fr\/transactions-et-causes\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Faillite de Grozelle\u00a0: Le tribunal ordonne le recouvrement des 21,5\u00a0millions de dollars \u00ab\u00a0gagn\u00e9s\u00a0\u00bb dans le cadre d\u2019une fraude de type Ponzi | Miller Thomson\" \/>\n<meta property=\"og:description\" content=\"Le 9&nbsp;f\u00e9vrier&nbsp;2026, la Cour sup\u00e9rieure de justice de l\u2019Ontario a publi\u00e9 ses motifs dans une d\u00e9cision importante pour le droit canadien de l\u2019insolvabilit\u00e9 dans l\u2019affaire de la faillite de Douglas Grozelle (2026&nbsp;ONSC&nbsp;758). La Cour a accueilli une demande d\u00e9pos\u00e9e par Grant Thornton Limited, en sa qualit\u00e9 de syndic de faillite de Douglas Grozelle, visant \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.millerthomson.com\/fr\/transactions-et-causes\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\/\" \/>\n<meta property=\"og:site_name\" content=\"Miller Thomson\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MillerThomsonLaw\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-17T14:23:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@millerthomson\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/transactions-et-causes\\\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\\\/\",\"url\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/transactions-et-causes\\\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\\\/\",\"name\":\"Faillite de Grozelle\u00a0: Le tribunal ordonne le recouvrement des 21,5\u00a0millions de dollars \u00ab\u00a0gagn\u00e9s\u00a0\u00bb dans le cadre d\u2019une fraude de type Ponzi | Miller Thomson\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#website\"},\"datePublished\":\"2026-02-09T13:58:00+00:00\",\"dateModified\":\"2026-02-17T14:23:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/transactions-et-causes\\\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/transactions-et-causes\\\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/transactions-et-causes\\\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transactions et mandats\",\"item\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/transactions-et-causes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Faillite de Grozelle\u00a0: Le tribunal ordonne le recouvrement des 21,5\u00a0millions de dollars \u00ab\u00a0gagn\u00e9s\u00a0\u00bb dans le cadre d\u2019une fraude de type Ponzi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/\",\"name\":\"Miller Thomson | Cabinet de droit des affaires pancanadien\",\"description\":\"National law firm providing business law expertise and litigation and disputes services for businesses across Canada since 1957.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#organization\",\"name\":\"Miller Thomson | Cabinet de droit des affaires pancanadien\",\"url\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.millerthomson.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/miller-thomson.svg\",\"contentUrl\":\"https:\\\/\\\/www.millerthomson.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/miller-thomson.svg\",\"width\":380,\"height\":50,\"caption\":\"Miller Thomson | Cabinet de droit des affaires pancanadien\"},\"image\":{\"@id\":\"https:\\\/\\\/www.millerthomson.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MillerThomsonLaw\\\/\",\"https:\\\/\\\/x.com\\\/millerthomson\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/miller-thomson-llp\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@millerthomson\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Faillite de Grozelle\u00a0: Le tribunal ordonne le recouvrement des 21,5\u00a0millions de dollars \u00ab\u00a0gagn\u00e9s\u00a0\u00bb dans le cadre d\u2019une fraude de type Ponzi | Miller Thomson","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.millerthomson.com\/fr\/transactions-et-causes\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\/","og_locale":"fr_FR","og_type":"article","og_title":"Faillite de Grozelle\u00a0: Le tribunal ordonne le recouvrement des 21,5\u00a0millions de dollars \u00ab\u00a0gagn\u00e9s\u00a0\u00bb dans le cadre d\u2019une fraude de type Ponzi | Miller Thomson","og_description":"Le 9&nbsp;f\u00e9vrier&nbsp;2026, la Cour sup\u00e9rieure de justice de l\u2019Ontario a publi\u00e9 ses motifs dans une d\u00e9cision importante pour le droit canadien de l\u2019insolvabilit\u00e9 dans l\u2019affaire de la faillite de Douglas Grozelle (2026&nbsp;ONSC&nbsp;758). La Cour a accueilli une demande d\u00e9pos\u00e9e par Grant Thornton Limited, en sa qualit\u00e9 de syndic de faillite de Douglas Grozelle, visant \u00e0 [&hellip;]","og_url":"https:\/\/www.millerthomson.com\/fr\/transactions-et-causes\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\/","og_site_name":"Miller Thomson","article_publisher":"https:\/\/www.facebook.com\/MillerThomsonLaw\/","article_modified_time":"2026-02-17T14:23:21+00:00","twitter_card":"summary_large_image","twitter_site":"@millerthomson","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.millerthomson.com\/fr\/transactions-et-causes\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\/","url":"https:\/\/www.millerthomson.com\/fr\/transactions-et-causes\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\/","name":"Faillite de Grozelle\u00a0: Le tribunal ordonne le recouvrement des 21,5\u00a0millions de dollars \u00ab\u00a0gagn\u00e9s\u00a0\u00bb dans le cadre d\u2019une fraude de type Ponzi | Miller Thomson","isPartOf":{"@id":"https:\/\/www.millerthomson.com\/fr\/#website"},"datePublished":"2026-02-09T13:58:00+00:00","dateModified":"2026-02-17T14:23:21+00:00","breadcrumb":{"@id":"https:\/\/www.millerthomson.com\/fr\/transactions-et-causes\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.millerthomson.com\/fr\/transactions-et-causes\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.millerthomson.com\/fr\/transactions-et-causes\/court-orders-recovery-of-21-5-million-in-winner-profits-in-grozelle-ponzi-scheme-bankruptcy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.millerthomson.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Transactions et mandats","item":"https:\/\/www.millerthomson.com\/fr\/transactions-et-causes\/"},{"@type":"ListItem","position":3,"name":"Faillite de Grozelle\u00a0: Le tribunal ordonne le recouvrement des 21,5\u00a0millions de dollars \u00ab\u00a0gagn\u00e9s\u00a0\u00bb dans le cadre d\u2019une fraude de type Ponzi"}]},{"@type":"WebSite","@id":"https:\/\/www.millerthomson.com\/fr\/#website","url":"https:\/\/www.millerthomson.com\/fr\/","name":"Miller Thomson | Cabinet de droit des affaires pancanadien","description":"National law firm providing business law expertise and litigation and disputes services for businesses across Canada since 1957.","publisher":{"@id":"https:\/\/www.millerthomson.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.millerthomson.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.millerthomson.com\/fr\/#organization","name":"Miller Thomson | Cabinet de droit des affaires pancanadien","url":"https:\/\/www.millerthomson.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.millerthomson.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/miller-thomson.svg","contentUrl":"https:\/\/www.millerthomson.com\/wp-content\/uploads\/2024\/10\/miller-thomson.svg","width":380,"height":50,"caption":"Miller Thomson | Cabinet de droit des affaires pancanadien"},"image":{"@id":"https:\/\/www.millerthomson.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MillerThomsonLaw\/","https:\/\/x.com\/millerthomson","https:\/\/www.linkedin.com\/company\/miller-thomson-llp\/","https:\/\/www.youtube.com\/@millerthomson"]}]}},"_links":{"self":[{"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/deals-cases\/46642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/deals-cases"}],"about":[{"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/types\/deals-cases"}],"author":[{"embeddable":true,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/users\/92"}],"version-history":[{"count":0,"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/deals-cases\/46642\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.millerthomson.com\/fr\/wp-json\/wp\/v2\/media?parent=46642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}